{"id":9653,"date":"2019-06-19T11:03:00","date_gmt":"2019-06-19T09:03:00","guid":{"rendered":"https:\/\/www.alit-tech.com\/?p=9653"},"modified":"2024-05-21T11:05:03","modified_gmt":"2024-05-21T09:05:03","slug":"psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive","status":"publish","type":"post","link":"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/","title":{"rendered":"PSP si affida alla nuova tecnologia a spruzzo Fastrip per trattare componenti automotive"},"content":{"rendered":"\n<p><em>PSP Sverniciature, uno dei pionieri in Italia della sverniciatura conto terzi, ha installato un impianto di sverniciatura Fastrip di ALIT.<\/em><\/p>\n\n\n\n<p>La macchina di sverniciatura messa a punto da ALIT si basa sulla&nbsp;<strong>tecnologia applicativa a spruzzo<\/strong>&nbsp;e risponde alle esigenze di&nbsp;<a href=\"https:\/\/www.pspsverniciature.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">PSP Sverniciature<\/a>&nbsp;di offrire, oltre alla sverniciatura di telai e accessori di verniciatura, anche la lavorazione di quei materiali che risultano di<\/p>\n\n\n\n<p>difficile gestione con le tecnologie criogenica e termica, come per esempio i manufatti in alluminio, di cui sono costituiti i componenti automotive e diversi oggetti di design, come maniglie e lampade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">I vantaggi della tecnologia a spruzzo<\/h2>\n\n\n\n<p>La tecnologia di applicazione a spruzzo assicura diversi vantaggi: richiede&nbsp;<strong>prodotti a basso impatto ambientale<\/strong>, che si attivano ad una temperatura di 120\u00b0C \u2013 quasi doppia rispetto ai processi ad immersione che avvengono a 50 o 60\u00b0C \u2013 ma presentano punti di infiammabilit\u00e0 molto elevati e non sono tossici.&nbsp;<\/p>\n\n\n\n<p>Hanno anche l\u2019ulteriore vantaggio di&nbsp;<strong>consentire un intervento di soft stripping<\/strong>, una sverniciatura leggera che non modifica la struttura molecolare del pezzo o la chimica del metallo, che pu\u00f2 cos\u00ec mantenere le caratteristiche peculiari di resistenza.<\/p>\n\n\n\n<p>L\u2019impianto di sverniciatura Fastrip \u00e8 utilizzato per il&nbsp;<strong>recupero di manufatti di ogni tipo di materiale<\/strong>, specialmente in alluminio e leghe simili, con difetti di verniciatura.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Il processo di sverniciatura<\/h2>\n\n\n\n<p>L\u2019impianto di sverniciatura \u00e8 un sistema modulare a vasca singola. I manufatti sono caricati all\u2019interno di un<\/p>\n\n\n\n<p>cestello introdotto nel primo dei due vani, dove sono trattati ad una temperatura di sverniciatura di 120\u00b0C. Durante la fase di spruzzatura del prodotto sverniciante, il cestello ruota di 360\u00b0C per una durata pari al tempo ciclo impostato, al termine del quale \u00e8 prevista una fase di aspirazione. Una volta verificato che tutti i pezzi caricati siano stati verniciati in modo corretto, si procede a togliere il cestello dalla vasca di sverniciatura per inserirlo in un\u2019altra vasca gemella che contiene acqua a 70\u00b0C, per favorire il risciacquo dei componenti. In questo modo, e dopo la verifica che i manufatti siano stati sverniciati secondo i requisiti richiesti, possono essere&nbsp;<strong>subito imballati e preparati per la riconsegna<\/strong>&nbsp;al cliente.<\/p>\n\n\n\n<p>La&nbsp;<strong>struttura modulare<\/strong>&nbsp;permette la sostituzione del solo bagno saturo, mantenendo in funzione la seconda vasca utilizzata per il lavaggio e il risciacquo dei pezzi: in questo modo&nbsp;<strong>non \u00e8 necessario sostituire l\u2019intera soluzione di sverniciatura<\/strong>.<\/p>\n\n\n\n<p>Oltre ad incontrare le esigenze di sverniciatura di PSP, i tecnici di ALIT hanno identificato altre criticit\u00e0 annesse a tale processo. Questo \u00e8 il motivo per cui abbiamo cercato di fornire a PSP&nbsp;<strong>un sistema completo e integrato con tutti i dispositivi utili<\/strong>&nbsp;a rendere questo tipo di processo economicamente gestibile ed ecosostenibile. Oltre alla nuova tecnologia di sverniciatura, i nostri tecnici hanno curato la progettazione e l\u2019installazione del&nbsp;<strong>sistema di riscaldamento a olio diatermico<\/strong>, dello&nbsp;<strong>scrubber per l\u2019abbattimento dei fumi<\/strong>&nbsp;e del&nbsp;<strong>dispositivo per il trattamento delle morchie<\/strong>.&nbsp;<\/p>\n\n\n\n<p>\u201cGrazie all\u2019impianto Fastrip la diversit\u00e0 dei materiali con cui sono realizzati ed i tentativi di recupero dei difetti di&nbsp;<\/p>\n\n\n\n<p>verniciatura effettuati dall\u2019applicatore non rappresentano pi\u00f9 un problema: la velocit\u00e0 di rimozione del film di<\/p>\n\n\n\n<p>vernice difettosa ed il trattamento multimetal dell\u2019impianto hanno risolto queste criticit\u00e0 e semplificato il processo, rivoluzionando il modo con cui sono state concepite finora le operazioni di sverniciatura\u201d, afferma Massimiliano Prederi, titolare di PSP Sverniciature.&nbsp;<\/p>\n\n\n\n<p>Leggi l\u2019articolo completo pubblicato sulla rivista internazionale di trattamenti superficiali\u00a0<a href=\"https:\/\/www.ipcm.it\/it\/riviste-ipcm\/\" target=\"_blank\" rel=\"noreferrer noopener\">ipcm\u00ae International Paint&amp;Coating Magazine<\/a>, n. 57 (Maggio\/Giugno 2019), e\u00a0<a href=\"\/it\/contatti\/\">contattaci<\/a>\u00a0per ulteriori informazioni!<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<iframe allowfullscreen allow=\"fullscreen\" style=\"border:none;width:100%;height:326px;\" src=\"\/\/e.issuu.com\/embed.html?d=15284827-ipcm-2019-57&#038;hideIssuuLogo=true&#038;pageNumber=122&#038;showOtherPublicationsAsSuggestions=true&#038;u=ipcm\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>PSP Sverniciature, uno dei pionieri in Italia della sverniciatura conto terzi, ha installato un impianto di sverniciatura Fastrip di ALIT. La macchina di sverniciatura messa a punto da ALIT si basa sulla&nbsp;tecnologia applicativa a spruzzo&nbsp;e risponde alle esigenze di&nbsp;PSP Sverniciature&nbsp;di offrire, oltre alla sverniciatura di telai e accessori di verniciatura, anche la lavorazione di quei [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9571,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rassegna-stampa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PSP si affida alla nuova tecnologia a spruzzo Fastrip per trattare componenti automotive - Alit technologies Spa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PSP si affida alla nuova tecnologia a spruzzo Fastrip per trattare componenti automotive - Alit technologies Spa\" \/>\n<meta property=\"og:description\" content=\"PSP Sverniciature, uno dei pionieri in Italia della sverniciatura conto terzi, ha installato un impianto di sverniciatura Fastrip di ALIT. La macchina di sverniciatura messa a punto da ALIT si basa sulla&nbsp;tecnologia applicativa a spruzzo&nbsp;e risponde alle esigenze di&nbsp;PSP Sverniciature&nbsp;di offrire, oltre alla sverniciatura di telai e accessori di verniciatura, anche la lavorazione di quei [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/\" \/>\n<meta property=\"og:site_name\" content=\"Alit technologies Spa\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-19T09:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-21T09:05:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alit-tech.com\/wp-content\/uploads\/2024\/05\/PSP-by-Alit_Anteprima.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adm1n_alit_1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"adm1n_alit_1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/\",\"url\":\"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/\",\"name\":\"PSP si affida alla nuova tecnologia a spruzzo Fastrip per trattare componenti automotive - Alit technologies Spa\",\"isPartOf\":{\"@id\":\"https:\/\/alit-tech.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/alit-tech.com\/wp-content\/uploads\/2024\/05\/PSP-by-Alit_Anteprima.jpg\",\"datePublished\":\"2019-06-19T09:03:00+00:00\",\"dateModified\":\"2024-05-21T09:05:03+00:00\",\"author\":{\"@id\":\"https:\/\/alit-tech.com\/it\/#\/schema\/person\/617bac32a108627e66194620e7b717c6\"},\"breadcrumb\":{\"@id\":\"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/#primaryimage\",\"url\":\"https:\/\/alit-tech.com\/wp-content\/uploads\/2024\/05\/PSP-by-Alit_Anteprima.jpg\",\"contentUrl\":\"https:\/\/alit-tech.com\/wp-content\/uploads\/2024\/05\/PSP-by-Alit_Anteprima.jpg\",\"width\":700,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/alit-tech.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PSP si affida alla nuova tecnologia a spruzzo Fastrip per trattare componenti automotive\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/alit-tech.com\/it\/#website\",\"url\":\"https:\/\/alit-tech.com\/it\/\",\"name\":\"Alit technologies Spa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/alit-tech.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/alit-tech.com\/it\/#\/schema\/person\/617bac32a108627e66194620e7b717c6\",\"name\":\"adm1n_alit_1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/alit-tech.com\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/alit-tech.com\/wp-content\/litespeed\/avatar\/bcf483e171993b692572c53763702a38.jpg?ver=1778605854\",\"contentUrl\":\"https:\/\/alit-tech.com\/wp-content\/litespeed\/avatar\/bcf483e171993b692572c53763702a38.jpg?ver=1778605854\",\"caption\":\"adm1n_alit_1\"},\"sameAs\":[\"https:\/\/www.alit-tech.com\"],\"url\":\"https:\/\/alit-tech.com\/it\/author\/adm1n_alit_1\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PSP si affida alla nuova tecnologia a spruzzo Fastrip per trattare componenti automotive - Alit technologies Spa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/","og_locale":"it_IT","og_type":"article","og_title":"PSP si affida alla nuova tecnologia a spruzzo Fastrip per trattare componenti automotive - Alit technologies Spa","og_description":"PSP Sverniciature, uno dei pionieri in Italia della sverniciatura conto terzi, ha installato un impianto di sverniciatura Fastrip di ALIT. La macchina di sverniciatura messa a punto da ALIT si basa sulla&nbsp;tecnologia applicativa a spruzzo&nbsp;e risponde alle esigenze di&nbsp;PSP Sverniciature&nbsp;di offrire, oltre alla sverniciatura di telai e accessori di verniciatura, anche la lavorazione di quei [&hellip;]","og_url":"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/","og_site_name":"Alit technologies Spa","article_published_time":"2019-06-19T09:03:00+00:00","article_modified_time":"2024-05-21T09:05:03+00:00","og_image":[{"width":700,"height":500,"url":"https:\/\/alit-tech.com\/wp-content\/uploads\/2024\/05\/PSP-by-Alit_Anteprima.jpg","type":"image\/jpeg"}],"author":"adm1n_alit_1","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"adm1n_alit_1","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/","url":"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/","name":"PSP si affida alla nuova tecnologia a spruzzo Fastrip per trattare componenti automotive - Alit technologies Spa","isPartOf":{"@id":"https:\/\/alit-tech.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/#primaryimage"},"image":{"@id":"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/#primaryimage"},"thumbnailUrl":"https:\/\/alit-tech.com\/wp-content\/uploads\/2024\/05\/PSP-by-Alit_Anteprima.jpg","datePublished":"2019-06-19T09:03:00+00:00","dateModified":"2024-05-21T09:05:03+00:00","author":{"@id":"https:\/\/alit-tech.com\/it\/#\/schema\/person\/617bac32a108627e66194620e7b717c6"},"breadcrumb":{"@id":"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/#primaryimage","url":"https:\/\/alit-tech.com\/wp-content\/uploads\/2024\/05\/PSP-by-Alit_Anteprima.jpg","contentUrl":"https:\/\/alit-tech.com\/wp-content\/uploads\/2024\/05\/PSP-by-Alit_Anteprima.jpg","width":700,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/alit-tech.com\/it\/rassegna-stampa\/psp-si-affida-alla-nuova-tecnologia-a-spruzzo-fastrip-per-trattare-componenti-automotive\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alit-tech.com\/it\/"},{"@type":"ListItem","position":2,"name":"PSP si affida alla nuova tecnologia a spruzzo Fastrip per trattare componenti automotive"}]},{"@type":"WebSite","@id":"https:\/\/alit-tech.com\/it\/#website","url":"https:\/\/alit-tech.com\/it\/","name":"Alit technologies Spa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alit-tech.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/alit-tech.com\/it\/#\/schema\/person\/617bac32a108627e66194620e7b717c6","name":"adm1n_alit_1","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/alit-tech.com\/it\/#\/schema\/person\/image\/","url":"https:\/\/alit-tech.com\/wp-content\/litespeed\/avatar\/bcf483e171993b692572c53763702a38.jpg?ver=1778605854","contentUrl":"https:\/\/alit-tech.com\/wp-content\/litespeed\/avatar\/bcf483e171993b692572c53763702a38.jpg?ver=1778605854","caption":"adm1n_alit_1"},"sameAs":["https:\/\/www.alit-tech.com"],"url":"https:\/\/alit-tech.com\/it\/author\/adm1n_alit_1\/"}]}},"_links":{"self":[{"href":"https:\/\/alit-tech.com\/it\/wp-json\/wp\/v2\/posts\/9653"}],"collection":[{"href":"https:\/\/alit-tech.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alit-tech.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alit-tech.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alit-tech.com\/it\/wp-json\/wp\/v2\/comments?post=9653"}],"version-history":[{"count":1,"href":"https:\/\/alit-tech.com\/it\/wp-json\/wp\/v2\/posts\/9653\/revisions"}],"predecessor-version":[{"id":9654,"href":"https:\/\/alit-tech.com\/it\/wp-json\/wp\/v2\/posts\/9653\/revisions\/9654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alit-tech.com\/it\/wp-json\/wp\/v2\/media\/9571"}],"wp:attachment":[{"href":"https:\/\/alit-tech.com\/it\/wp-json\/wp\/v2\/media?parent=9653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alit-tech.com\/it\/wp-json\/wp\/v2\/categories?post=9653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alit-tech.com\/it\/wp-json\/wp\/v2\/tags?post=9653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}